{"id":42,"date":"2016-06-29T15:38:37","date_gmt":"2016-06-29T15:38:37","guid":{"rendered":"http:\/\/buzosderegatas.com.ar\/bitacora\/?p=42"},"modified":"2016-06-29T15:45:19","modified_gmt":"2016-06-29T15:45:19","slug":"cozumel-2016-los-buzos-no-piden-permiso-parte-5","status":"publish","type":"post","link":"http:\/\/buzosderegatas.com.ar\/bitacora\/2016\/06\/29\/cozumel-2016-los-buzos-no-piden-permiso-parte-5\/","title":{"rendered":"Cozumel 2016 \u2013 Los Buzos no piden permiso (Parte 5)"},"content":{"rendered":"<p>Parte 5: \u00a0<strong>Marina, la del barrio\u2026 <\/strong><\/p>\n<p>Sombrero tipo compadrito apilusado, remera verde tarareada, bermuda Camel Trophy en tr\u00e1mite de jubilaci\u00f3n, zoquetes envi\u00f3n excedidos de fecha de vencimiento y ojotas de alg\u00fan d\u00eda del padre del anterior siglo\u2026<\/p>\n<p>As\u00ed mateaba, indiferente bajo alguna sombrilla discreta del Hotel de playa del Carmen, \u201cel maraj\u00e1 de los buzos\u201d, \u201cel palad\u00edn de la justicia manobrera\u201d, \u201cel ladr\u00f3n de latidos de distra\u00eddas cincuenteranas paranaenses\u201d\u2026<\/p>\n<p>\u201cel Excelent\u00edsimo Fervi\u201d\u2026 portando en su mano un libro ya algo mareado de tanto paseo\u2026<\/p>\n<p>Un poco m\u00e1s hacia el mar, entre los natatorios junto al \u201cQuincho\u201d, estaba tomando sol el \u201cMono\u201d, valga la redundancia. Como suele suceder en estos casos, Don Felipe\u2026 perd\u00f3n, Don Francisco, aglutin\u00f3 en pocos minutos a la masa de regatenses que merodeaban y se acercaban en b\u00fasqueda de conversaci\u00f3n, an\u00e9cdotas, compartir un buen momento\u2026 es decir, al rato nom\u00e1s hab\u00eda varios que ya se quer\u00edan matar\u2026<\/p>\n<p>Casi imperceptible, sentado bajo las arcadas junto a la barra perimetral del bar, observando al grupo, estaba<\/p>\n<p>\u201c\u00e9l\u201d\u2026<\/p>\n<p>masticando un tentempi\u00e9 con cara misteriosa, dando aspecto similar a una mezcla de Mr. Bean y Freddy Kruegger, gesto adusto y espeluznante t\u00edpico de quien posee esa cruza fat\u00eddica de Asesino serial y ped\u00f3filo al pedo,<\/p>\n<p>\u201c\u00e9l\u201d\u2026<\/p>\n<p>planeando la ins\u00f3lita posibilidad de la nada\u2026 buscando sin pretender encontrar\u2026 escuchando voces que no est\u00e1n\u2026<\/p>\n<p>\u201c\u00e9l\u201d\u2026<\/p>\n<p>promotor de su propia falta de protagonismo\u2026 modesto intelectual que naufraga en sus propias corrientes del saber\u2026<\/p>\n<p>\u201c\u00e9l\u201d\u2026<\/p>\n<p>-\u201c\u2026 pero dale pelotudo\u2026 \u00bfqui\u00e9n es \u00e9l?&#8230; y la puta que te pari\u00f3&#8230;\u201d<\/p>\n<p>Dejando de lado la agresi\u00f3n, y lamentando la falta de paciencia y capacidad de reconocimiento, comento, lo que la mayor\u00eda ya sabr\u00e1, que\u2026<\/p>\n<p>\u201c\u00e9l\u201d\u2026<\/p>\n<p>es Nano\u2026 \u00bfqui\u00e9n otro?<\/p>\n<p>&nbsp;<\/p>\n<p>-\u201c\u2026 Hola, holaaa\u2026\u201d salud\u00f3 G\u00fcesito con cara de haber boludeado bastante\u2026<\/p>\n<p>-\u201c\u2026 hola\u2026\u201d dijo Patricia<\/p>\n<p>-\u201c\u2026 hola\u2026\u201d dijo Mat\u00edas<\/p>\n<p>-\u201c\u2026 hola&#8230;\u201d dijo Mara<\/p>\n<p>-\u201c\u2026 hola&#8230;\u201d dijo Ernesto<\/p>\n<p>\u2026 y as\u00ed sucesivamente\u2026 (No describo m\u00e1s saludos por el lector impaciente&#8230;)<\/p>\n<p>Las reposeras mojaban sus patas en la plataforma menos profunda de la piscina mientras sus ocupantes se tostaban al son de algunos boleros\u2026 y algunos con los boleros al sol\u2026<\/p>\n<p>De repente\u2026<\/p>\n<p>-\u201c\u2026 miraaaa Marina, quienes est\u00e1nnnnn\u2026\u201d expres\u00f3 mal actuadamente Lito arribando al grupo\u2026 \u201c\u2026 hola Federico queriiidoooo\u2026 hola Fernanda queriiidaaa\u2026 hola Carlitos queriiidoooo\u2026 Iriiiaaaa\u2026\u201d etc\u2026 etc\u2026<\/p>\n<p>Marina, iba asintiendo con la cabeza cada saludo con carita de p\u00f3ker.<\/p>\n<p>-\u201c\u2026 mir\u00e1 Marina, pero qu\u00e9 casualidad encontrarnos\u2026\u201d insisti\u00f3 Lito sonriendo a su mujer y reboleando ojos al resto\u2026<\/p>\n<p>El grupo at\u00f3nito y paralizado, obviamente no sab\u00eda qu\u00e9 hacer. Esos segundos de incertidumbre que no pasan nunca y se inmortalizan siempre\u2026<\/p>\n<p>Hasta que\u2026<\/p>\n<p>-\u201c\u2026 holaaaaa\u2026 que alegre coincidencia\u2026\u201d desliz\u00f3 Marina para tranquilidad de la platea est\u00e1tica y bronceada\u2026 y por sobre todo para un Lito, que ahora ya sin presi\u00f3n, sali\u00f3 como Balma\u2026 (Perd\u00f3n, nada que ver), sali\u00f3 como b\u00f3lido hacia el parque del hotel vecino a afanar orqu\u00eddeas\u2026<\/p>\n<p>-\u201c\u2026 para festejar este encuentro, esta noche vamos todos a Coco Bongo\u2026\u201d dijo con entusiasmo Santiago mientras recib\u00eda un codazo de Rosana a escasa altura\u2026<\/p>\n<p>\u201cVAMOS\u2026\u201d respondi\u00f3 al un\u00edsono la gran mayor\u00eda con mucho entusiasmo y sin la menor idea de lo que era Coco Bongo\u2026<\/p>\n<p>-\u201c\u2026 nosotros no iremos\u2026\u201d sentenci\u00f3 Mat\u00edas mientras le hac\u00eda a su pareja un gui\u00f1o c\u00f3mplice de un trasnochar t\u00e1ntrico\u2026 se\u00f1a que ella desestim\u00f3 de cuajo para no ilusionarse al pedo.<\/p>\n<p>-\u201c\u2026 yo prefiero quedarme\u2026\u201ddecidi\u00f3 Fervi y girando sobre sus ojotas apunt\u00f3 el paso hacia una pebeta de 72 que estaba bastante desarrugada\u2026<\/p>\n<p>-\u201c\u2026 yo no voy a Coco Porongo\u2026\u201d dijo Juan con cara negativa\u2026<\/p>\n<p>-\u201c\u2026 es Coco Bongo Juan\u2026\u201d aclar\u00f3 Augusto mientras le entraba a la cerveza\u2026<\/p>\n<p>-\u201c\u2026 bueno\u2026 eso\u2026 no voy a Hongo Bongo\u2026\u201d<\/p>\n<p>-\u201c\u2026 Juan\u2026 es Coco Booongoooo\u2026\u201d grit\u00f3 amenazante Nano desde el bar\u2026<\/p>\n<p>-\u201c\u2026 Si\u2026 bueno\u2026 tranquilo\u2026 no ir\u00e9 a Coco Chongo\u2026\u201d<\/p>\n<p>-\u201c\u2026 se nota que hace tiempo que Juan no va a R\u00edo de Janeiro\u2026\u201d coment\u00f3 por lo bajo Luis haciendo un fondo blanco de ron\u2026<\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>No estaba programado pero\u2026 Continuar\u00e1\u2026<\/strong><\/em><\/p>\n<p><span style=\"color: #ff0000;\">PD: ya nadie pregunta por \u00c1ngeles y Exequiel\u2026<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parte 5: \u00a0Marina, la del barrio\u2026 Sombrero tipo compadrito apilusado, remera verde tarareada, bermuda Camel Trophy en tr\u00e1mite de jubilaci\u00f3n,[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[9,8,11,10],"class_list":["post-42","post","type-post","status-publish","format-standard","hentry","category-viajes","tag-buzos-de-regatas","tag-cozumel-2016","tag-culebron","tag-viajes"],"_links":{"self":[{"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/posts\/42","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/comments?post=42"}],"version-history":[{"count":2,"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/posts\/42\/revisions"}],"predecessor-version":[{"id":44,"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/posts\/42\/revisions\/44"}],"wp:attachment":[{"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/media?parent=42"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/categories?post=42"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/buzosderegatas.com.ar\/bitacora\/wp-json\/wp\/v2\/tags?post=42"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}